{"id":2576,"date":"2023-02-16T06:45:53","date_gmt":"2023-02-16T06:45:53","guid":{"rendered":"https:\/\/www.c-tl.com\/product\/figure-a-2\/"},"modified":"2024-01-02T07:33:56","modified_gmt":"2024-01-02T07:33:56","slug":"figure-a-2","status":"publish","type":"product","link":"https:\/\/www.c-tl.com\/en\/product\/figure-a-2\/","title":{"rendered":"Figure. A"},"content":{"rendered":"\t<section class=\"section\" id=\"section_1694244123\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\t\t<div class=\"tabbed-content\">\n\t\t\t\n\t\t\t<ul class=\"nav nav-tabs nav-uppercase nav-size-xlarge nav-left\" role=\"tablist\"><li id=\"tab-specification\" class=\"tab active has-icon\" role=\"presentation\"><a href=\"#tab_specification\" role=\"tab\" aria-selected=\"true\" aria-controls=\"tab_specification\"><span>Specification<\/span><\/a><\/li><\/ul><div class=\"tab-panels\"><div id=\"tab_specification\" class=\"panel active entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-specification\">\n<div class=\"row\"  id=\"row-1285351076\">\n\n\t<div id=\"col-1069013225\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2525818606\" class=\"text\">\n\t\t\n<p style=\"text-align: left;\"><strong><span style=\"font-size: 160%; color: #8179a8;\">Specification<\/span><\/strong><\/p>\n\t\t\n<style>\n#text-2525818606 {\n  line-height: 0.75;\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"background-color:rgb(129, 121, 168);\"><\/div>\n\t<div id=\"gap-1526296554\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1526296554 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row row-collapse\"  id=\"row-383937315\">\n\n\t<div id=\"col-1690203311\" class=\"col medium-4 small-4 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><strong><span style=\"font-size: 110%; color: #000000;\">Mode of operation<\/span><\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-859547594\" class=\"col medium-8 small-8 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 110%; color: #000000;\">:\u00a0 \u00a0Non-Maintained<br \/>\n<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2109791757\" class=\"col medium-4 small-4 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><strong><span style=\"font-size: 110%; color: #000000;\">Main supply <\/span><\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2043506647\" class=\"col medium-8 small-8 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 110%; color: #000000;\">:\u00a0 \u00a0AC 220 Volt, 50 Hz, \u00b110% Single Phase<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-101414453\" class=\"col medium-4 small-4 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><strong><span style=\"font-size: 110%; color: #000000;\">For Lamp <\/span><\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1917373305\" class=\"col medium-8 small-8 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 110%; color: #000000;\">:\u00a0 \u00a0Remote lamp 12VDC \/ 24VDC<br \/>\n<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1156562658\" class=\"col medium-4 small-4 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><strong><span style=\"font-size: 110%; color: #000000;\">Battery<\/span><\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1247997446\" class=\"col medium-8 small-8 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 110%; color: #000000;\">:\u00a0 \u00a0Sealed lead acid battery<br \/>\u00a0 \u00a0 ISO 9001, ISO 14001 and UL certified<br \/><\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1654288733\" class=\"col medium-4 small-4 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><strong><span style=\"font-size: 110%; color: #000000;\">Charger <\/span><\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1196177679\" class=\"col medium-8 small-8 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 110%; color: #000000;\">:\u00a0 \u00a0Solid state system automatic battery charger<br \/>:\u00a0 \u00a0Constant voltage charging system<br \/><\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1554147978\" class=\"col medium-4 small-4 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><strong><span style=\"font-size: 110%; color: #000000;\">Charging time <\/span><\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-424272465\" class=\"col medium-8 small-8 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 110%; color: #000000;\">:\u00a0 \u00a012-15 Hours<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1682781429\" class=\"col medium-4 small-4 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><strong><span style=\"font-size: 110%; color: #000000;\">Construction<\/span><\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1430733452\" class=\"col medium-8 small-8 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 110%; color: #000000;\">:\u00a0 \u00a0Electro-Galvanized steel sheet 1.2 mm.<br \/>\u00a0 \u00a0 epoxy powder and stove enamel coated<br \/><\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-935948611\" class=\"col medium-4 small-4 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><strong><span style=\"font-size: 110%; color: #000000;\">Safety features <\/span><\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-274146675\" class=\"col medium-8 small-8 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 110%; color: #000000;\">:\u00a0 \u00a0anti-rust corrosion proof<br \/>:\u00a0 \u00a0Automatic High-low voltage cut-off<br \/>:\u00a0 \u00a0AC fuse- preventing AC Line 220 Volt short circuit and overload<br \/>:\u00a0 \u00a0DC fuse- preventing charging short circuit<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-296167887\" class=\"col medium-4 small-4 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><strong><span style=\"font-size: 110%; color: #000000;\">Accessory <\/span><\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-392000842\" class=\"col medium-8 small-8 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 110%; color: #000000;\">:\u00a0 \u00a0DC load- preventing overload and short circuit for lamp<br \/>\n:\u00a0 \u00a0Infrared remote test<br \/>\n:\u00a0 \u00a0AC indicator for AC Line 220 Volt<br \/>\n:\u00a0 \u00a0Charge\/Full indicator for charge battery<br \/>\n:\u00a0 \u00a0Fail indicator for charge syste<br \/>\n:\u00a0 \u00a0DC voltmeter indicator for battery voltage<br \/>\n:\u00a0 \u00a0DC ammeter indicator for charge current<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse\"  id=\"row-1775721003\">\n\n\t<div id=\"col-23211420\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_560471396\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"388\" src=\"https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/02\/detail-19-1400x533.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/02\/detail-19-1400x533.jpg 1400w, https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/02\/detail-19-800x304.jpg 800w, https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/02\/detail-19-768x292.jpg 768w, https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/02\/detail-19-1536x584.jpg 1536w, https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/02\/detail-19-600x228.jpg 600w, https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/02\/detail-19.jpg 1848w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_560471396 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1682075910\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1098460229\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"568\" src=\"https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/02\/detail-20-1400x780.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/02\/detail-20-1400x780.jpg 1400w, https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/02\/detail-20-718x400.jpg 718w, https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/02\/detail-20-768x428.jpg 768w, https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/02\/detail-20-1536x856.jpg 1536w, https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/02\/detail-20-600x334.jpg 600w, https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/02\/detail-20.jpg 1942w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1098460229 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<\/div><\/div><\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1694244123 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n#section_1694244123 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1694244123 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-size: 120%;\">EMERGENCY POWER SYSTEM<\/span><\/p>\n","protected":false},"featured_media":814,"template":"","meta":[],"product_cat":[57],"product_tag":[],"class_list":["post-2576","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-central-emergency-power-unit-cu-series-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Figure. A - ctl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.c-tl.com\/en\/product\/figure-a-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Figure. A - ctl\" \/>\n<meta property=\"og:description\" content=\"EMERGENCY POWER SYSTEM\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.c-tl.com\/en\/product\/figure-a-2\/\" \/>\n<meta property=\"og:site_name\" content=\"ctl\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MaxBrightbyCEE\/?ref=embed_page\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-02T07:33:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/02\/Figure.-A-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1250\" \/>\n\t<meta property=\"og:image:height\" content=\"1251\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.c-tl.com\/en\/product\/figure-a-2\/\",\"url\":\"https:\/\/www.c-tl.com\/en\/product\/figure-a-2\/\",\"name\":\"Figure. A - ctl\",\"isPartOf\":{\"@id\":\"https:\/\/www.c-tl.com\/#website\"},\"datePublished\":\"2023-02-16T06:45:53+00:00\",\"dateModified\":\"2024-01-02T07:33:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.c-tl.com\/en\/product\/figure-a-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.c-tl.com\/en\/product\/figure-a-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.c-tl.com\/en\/product\/figure-a-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.c-tl.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Product\",\"item\":\"https:\/\/www.c-tl.com\/en\/product\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Figure. A\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.c-tl.com\/#website\",\"url\":\"https:\/\/www.c-tl.com\/\",\"name\":\"ctl\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.c-tl.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.c-tl.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.c-tl.com\/#organization\",\"name\":\"\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e04\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19 \u0e2f\u0e25\u0e2f \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32\u0e01\u0e27\u0e48\u0e32 20 \u0e1b\u0e35\",\"url\":\"https:\/\/www.c-tl.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.c-tl.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/05\/logo-e1683508859204.png\",\"contentUrl\":\"https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/05\/logo-e1683508859204.png\",\"width\":212,\"height\":100,\"caption\":\"\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e04\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19 \u0e2f\u0e25\u0e2f \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32\u0e01\u0e27\u0e48\u0e32 20 \u0e1b\u0e35\"},\"image\":{\"@id\":\"https:\/\/www.c-tl.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MaxBrightbyCEE\/?ref=embed_page\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Figure. A - ctl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.c-tl.com\/en\/product\/figure-a-2\/","og_locale":"en_US","og_type":"article","og_title":"Figure. A - ctl","og_description":"EMERGENCY POWER SYSTEM","og_url":"https:\/\/www.c-tl.com\/en\/product\/figure-a-2\/","og_site_name":"ctl","article_publisher":"https:\/\/www.facebook.com\/MaxBrightbyCEE\/?ref=embed_page","article_modified_time":"2024-01-02T07:33:56+00:00","og_image":[{"width":1250,"height":1251,"url":"https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/02\/Figure.-A-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.c-tl.com\/en\/product\/figure-a-2\/","url":"https:\/\/www.c-tl.com\/en\/product\/figure-a-2\/","name":"Figure. A - ctl","isPartOf":{"@id":"https:\/\/www.c-tl.com\/#website"},"datePublished":"2023-02-16T06:45:53+00:00","dateModified":"2024-01-02T07:33:56+00:00","breadcrumb":{"@id":"https:\/\/www.c-tl.com\/en\/product\/figure-a-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.c-tl.com\/en\/product\/figure-a-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.c-tl.com\/en\/product\/figure-a-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.c-tl.com\/en\/"},{"@type":"ListItem","position":2,"name":"Product","item":"https:\/\/www.c-tl.com\/en\/product\/"},{"@type":"ListItem","position":3,"name":"Figure. A"}]},{"@type":"WebSite","@id":"https:\/\/www.c-tl.com\/#website","url":"https:\/\/www.c-tl.com\/","name":"ctl","description":"","publisher":{"@id":"https:\/\/www.c-tl.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.c-tl.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.c-tl.com\/#organization","name":"\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e04\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19 \u0e2f\u0e25\u0e2f \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32\u0e01\u0e27\u0e48\u0e32 20 \u0e1b\u0e35","url":"https:\/\/www.c-tl.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.c-tl.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/05\/logo-e1683508859204.png","contentUrl":"https:\/\/www.c-tl.com\/wp-content\/uploads\/2023\/05\/logo-e1683508859204.png","width":212,"height":100,"caption":"\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e04\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19 \u0e2f\u0e25\u0e2f \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32\u0e01\u0e27\u0e48\u0e32 20 \u0e1b\u0e35"},"image":{"@id":"https:\/\/www.c-tl.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MaxBrightbyCEE\/?ref=embed_page"]}]}},"_links":{"self":[{"href":"https:\/\/www.c-tl.com\/en\/wp-json\/wp\/v2\/product\/2576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.c-tl.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.c-tl.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.c-tl.com\/en\/wp-json\/wp\/v2\/media\/814"}],"wp:attachment":[{"href":"https:\/\/www.c-tl.com\/en\/wp-json\/wp\/v2\/media?parent=2576"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.c-tl.com\/en\/wp-json\/wp\/v2\/product_cat?post=2576"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.c-tl.com\/en\/wp-json\/wp\/v2\/product_tag?post=2576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}